{"id":10691,"date":"2024-04-09T18:48:46","date_gmt":"2024-04-09T16:48:46","guid":{"rendered":"https:\/\/blog.ocasionplus.com\/?p=10691"},"modified":"2025-03-27T14:02:56","modified_gmt":"2025-03-27T13:02:56","slug":"facturacion-ocasionplus-2023","status":"publish","type":"post","link":"https:\/\/www.ocasionplus.com\/noticias\/facturacion-ocasionplus-2023\/","title":{"rendered":"La facturaci\u00f3n de OcasionPlus en 2023"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Durante el 2023 OcasionPlus <strong>bati\u00f3 su record hist\u00f3rico de ventas y factur\u00f3 430 millones de euros<\/strong>, un 54% m\u00e1s que en 2022, lo que supuso 140 millones de euros m\u00e1s que en el a\u00f1o anterior.\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el mercado de veh\u00edculos, OcasionPlus se destaca como una de las empresas referentes en el sector de coches de segunda mano. La compa\u00f1\u00eda ha experimentado un notable crecimiento en su facturaci\u00f3n, alcanzado un <strong>aumento del 54% en comparaci\u00f3n al 2023<\/strong>. Este logro se refleja en la <strong>venta de m\u00e1s de 25.000 unidades<\/strong> durante el \u00faltimo a\u00f1o, lo que represent\u00f3 una facturaci\u00f3n de 430 millones de euros, superando significativamente los 280 millones obtenidos en el 2022.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La trayectoria de OcasionPlus, desde su fundaci\u00f3n en el 2011, es una historia de \u00e9xito, caracterizada por un incremento constante en sus ingresos. La clave radica en su enfoque en la proximidad y atenci\u00f3n personalizada al cliente, tanto en el proceso de compra como en el servicio posventa. Esta filosof\u00eda de negocio ha permitido a la empresa expandirse a lo largo del territorio nacional, <strong><a href=\"https:\/\/www.ocasionplus.com\/concesionarios\">contando actualmente con 80 centros<\/a><\/strong> y pensando en la inauguraci\u00f3n de 14 nuevos concesionarios durante el 2023.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cat\u00e1logo de OcasionPlus est\u00e1 compuesto por <strong><a href=\"https:\/\/www.ocasionplus.com\/coches-ocasion\">m\u00e1s de 8.000 coches de segunda mano y seminuevos<\/a><\/strong>, ofrece una amplia variedad de marcas, modelos y tipos de combustible, asegurando satisfacer las necesidades de cada cliente. Mirando hacia el futuro, la empresa tiene previsto abrir 10 nuevos establecimientos en 2024, reafirmando su compromiso con la accesibilidad y la fidelizaci\u00f3n de su clientela.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fernando Rodr\u00edguez, CEO de OcasionPlus, atribuye el incremento en la facturaci\u00f3n a un cambio en la mentalidad de los consumidores, quienes ahora prefieren una opci\u00f3n de compra m\u00e1s r\u00e1pida y sin las demoras asociadas a la adquisici\u00f3n de veh\u00edculos nuevos. OcasionPlus responde a esta demanda ofreciendo acceso directo a una diversidad de marcas y modelos a precios competitivos en todos los concesionarios.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Los coches de segunda mano m\u00e1s vendidos por OcasionPlus en el 2023<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El mercado de autom\u00f3viles de ocasi\u00f3n ha sido testigo del dinamismo de OcasionPlus, que ha registrado una venta aproximada de 25.000 veh\u00edculos durante el 2023.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La preferencia de los consumidores se inclin\u00f3 hacia los coches compactos, que representaron el 40% de las ventas totales, aunque esto refleja una ligera disminuci\u00f3n del 3% en comparaci\u00f3n con el a\u00f1o anterior. Los SUV y todoterrenos siguieron en popularidad, con un 33% del total de ventas y un incremento del 7% respecto al 2022. Los monovol\u00famenes mantuvieron su cuota de mercado con un 11%, mientras que los veh\u00edculos familiares y los sedanes completaron el top 5 con un 6% y un 5% respectivamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En t\u00e9rminos de preferencias de combustible, los coches di\u00e9sel lideraron con un 48% de las ventas, aunque con una reducci\u00f3n del 1% en comparaci\u00f3n con el a\u00f1o previo. Los veh\u00edculos de gasolina ocuparon el segundo lugar con el 45%, seguidos por los coches h\u00edbridos que vieron duplicadas sus ventas, alcanzando un 5% del total.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los veh\u00edculos con etiqueta cero, como los h\u00edbridos enchufables y los el\u00e9ctricos, experimentaron un notable incremento en las ventas, con aumentos del 63% y 65% respectivamente, reflejando una clara tendencia de crecimiento en la demanda de estos veh\u00edculos, especialmente en \u00e1reas urbanas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La estrategia de OcasionPlus para el 2024<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">OcasionPlus se enfoca en enriquecer la experiencia de sus clientes durante 2024, poniendo especial atenci\u00f3n en los procesos de venta y posventa de veh\u00edculos de segunda mano. La empresa se compromete a ofrecer una experiencia libre de preocupaciones, garantizando una compra segura y protegida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con miras a este compromiso, OcasionPlus ha implementado tres medidas clave para asegurar la confianza total del cliente:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Acceso al inventario:<\/strong> Los clientes tienen la libertad de elegir entre un amplio inventario de 8.000 veh\u00edculos. Con una reserva de 300 euros, el coche seleccionado ser\u00e1 trasladado al concesionario m\u00e1s cercano, permitiendo al cliente inspeccionarlo y probarlo antes de realizar la compra.<\/li>\n\n\n\n<li><strong>Periodo de prueba:<\/strong> Se ofrece un periodo de prueba de 15 d\u00edas o 1.000 kil\u00f3metros, durante el cual el cliente puede verificar que el veh\u00edculo cumple con sus expectativas. En caso contrario, se facilitar\u00e1 el cambio por otro modelo o la devoluci\u00f3n completa del importe.<\/li>\n\n\n\n<li><strong>Mejoras en garant\u00edas:<\/strong> El departamento de garant\u00edas ha sido optimizado para proporcionar soluciones r\u00e1pidas y eficientes a cualquier inconveniente, sin implicar al cliente en los problemas internos, asegurando as\u00ed su satisfacci\u00f3n total.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Estas iniciativas reflejan el deseo de OcasionPlus de brindar una experiencia excepcional, donde la tranquilidad y la confianza del cliente son la prioridad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante el 2023 OcasionPlus bati\u00f3 su record hist\u00f3rico de ventas y factur\u00f3 430 millones de euros, un 54% m\u00e1s que en 2022, lo que supuso 140 millones de euros m\u00e1s que en el a\u00f1o anterior.\u00a0\u00a0 En el mercado de veh\u00edculos, OcasionPlus se destaca como una de las empresas referentes en el sector de coches de&#8230;<\/p>\n","protected":false},"author":2,"featured_media":10693,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-10691","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ocasionplus"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.8 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La facturaci\u00f3n de OcasionPlus en 2023 - OcasionPlus Blog<\/title>\n<meta name=\"description\" content=\"Durante el 2023, la facturaci\u00f3n de OcasionPlus incremento un 54% comparando con el a\u00f1o anterior. Este rendimiento se reflej\u00f3 en la venta de compactos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ocasionplus.com\/noticias\/facturacion-ocasionplus-2023\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La facturaci\u00f3n de OcasionPlus en 2023\" \/>\n<meta property=\"og:description\" content=\"Durante el 2023, la facturaci\u00f3n de OcasionPlus incremento un 54% comparando con el a\u00f1o anterior. Este rendimiento se reflej\u00f3 en la venta de compactos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ocasionplus.com\/noticias\/facturacion-ocasionplus-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"OcasionPlus Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ocasionplus\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-09T16:48:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-27T13:02:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/04\/IMG_0138-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"766\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"OcasionPlus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ocasionplus\" \/>\n<meta name=\"twitter:site\" content=\"@ocasionplus\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"OcasionPlus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/facturacion-ocasionplus-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/facturacion-ocasionplus-2023\\\/\"},\"author\":{\"name\":\"OcasionPlus\",\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#\\\/schema\\\/person\\\/7ab10ae859759ef2622b28e83ba868eb\"},\"headline\":\"La facturaci\u00f3n de OcasionPlus en 2023\",\"datePublished\":\"2024-04-09T16:48:46+00:00\",\"dateModified\":\"2025-03-27T13:02:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/facturacion-ocasionplus-2023\\\/\"},\"wordCount\":766,\"publisher\":{\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/facturacion-ocasionplus-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/IMG_0138-1-1.jpg\",\"articleSection\":[\"Actualidad OcasionPlus\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/facturacion-ocasionplus-2023\\\/\",\"url\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/facturacion-ocasionplus-2023\\\/\",\"name\":\"La facturaci\u00f3n de OcasionPlus en 2023 - OcasionPlus Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/facturacion-ocasionplus-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/facturacion-ocasionplus-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/IMG_0138-1-1.jpg\",\"datePublished\":\"2024-04-09T16:48:46+00:00\",\"dateModified\":\"2025-03-27T13:02:56+00:00\",\"description\":\"Durante el 2023, la facturaci\u00f3n de OcasionPlus incremento un 54% comparando con el a\u00f1o anterior. Este rendimiento se reflej\u00f3 en la venta de compactos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/facturacion-ocasionplus-2023\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/facturacion-ocasionplus-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/facturacion-ocasionplus-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/IMG_0138-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/IMG_0138-1-1.jpg\",\"width\":1280,\"height\":766,\"caption\":\"OcasionPlus Getafe es una de las tiendas que m\u00e1s vende de la empresa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/facturacion-ocasionplus-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ocasionplus.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La facturaci\u00f3n de OcasionPlus en 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#website\",\"url\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/\",\"name\":\"OcasionPlus Blog\",\"description\":\"Veh\u00edculos de ocasi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#organization\",\"name\":\"OcasionPlus\",\"url\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-cropped-oplus-logo-blog.png\",\"contentUrl\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-cropped-oplus-logo-blog.png\",\"width\":360,\"height\":71,\"caption\":\"OcasionPlus\"},\"image\":{\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ocasionplus\",\"https:\\\/\\\/x.com\\\/ocasionplus\",\"https:\\\/\\\/www.instagram.com\\\/ocasion_plus\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCBiCAto61Lyu27CgI95wrYQ\",\"https:\\\/\\\/www.tiktok.com\\\/@ocasionplus.com\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/ocasionplus\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#\\\/schema\\\/person\\\/7ab10ae859759ef2622b28e83ba868eb\",\"name\":\"OcasionPlus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/ocasionplus_avatar-96x96.jpg\",\"url\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/ocasionplus_avatar-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/ocasionplus_avatar-96x96.jpg\",\"caption\":\"OcasionPlus\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La facturaci\u00f3n de OcasionPlus en 2023 - OcasionPlus Blog","description":"Durante el 2023, la facturaci\u00f3n de OcasionPlus incremento un 54% comparando con el a\u00f1o anterior. Este rendimiento se reflej\u00f3 en la venta de compactos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ocasionplus.com\/noticias\/facturacion-ocasionplus-2023\/","og_locale":"es_ES","og_type":"article","og_title":"La facturaci\u00f3n de OcasionPlus en 2023","og_description":"Durante el 2023, la facturaci\u00f3n de OcasionPlus incremento un 54% comparando con el a\u00f1o anterior. Este rendimiento se reflej\u00f3 en la venta de compactos.","og_url":"https:\/\/www.ocasionplus.com\/noticias\/facturacion-ocasionplus-2023\/","og_site_name":"OcasionPlus Blog","article_publisher":"https:\/\/www.facebook.com\/ocasionplus","article_published_time":"2024-04-09T16:48:46+00:00","article_modified_time":"2025-03-27T13:02:56+00:00","og_image":[{"width":1280,"height":766,"url":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/04\/IMG_0138-1-1.jpg","type":"image\/jpeg"}],"author":"OcasionPlus","twitter_card":"summary_large_image","twitter_creator":"@ocasionplus","twitter_site":"@ocasionplus","twitter_misc":{"Escrito por":"OcasionPlus","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ocasionplus.com\/noticias\/facturacion-ocasionplus-2023\/#article","isPartOf":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/facturacion-ocasionplus-2023\/"},"author":{"name":"OcasionPlus","@id":"https:\/\/noticias.grupoocasionplus.com\/#\/schema\/person\/7ab10ae859759ef2622b28e83ba868eb"},"headline":"La facturaci\u00f3n de OcasionPlus en 2023","datePublished":"2024-04-09T16:48:46+00:00","dateModified":"2025-03-27T13:02:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/facturacion-ocasionplus-2023\/"},"wordCount":766,"publisher":{"@id":"https:\/\/noticias.grupoocasionplus.com\/#organization"},"image":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/facturacion-ocasionplus-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/04\/IMG_0138-1-1.jpg","articleSection":["Actualidad OcasionPlus"],"inLanguage":"es","copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.ocasionplus.com\/noticias\/facturacion-ocasionplus-2023\/","url":"https:\/\/www.ocasionplus.com\/noticias\/facturacion-ocasionplus-2023\/","name":"La facturaci\u00f3n de OcasionPlus en 2023 - OcasionPlus Blog","isPartOf":{"@id":"https:\/\/noticias.grupoocasionplus.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/facturacion-ocasionplus-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/facturacion-ocasionplus-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/04\/IMG_0138-1-1.jpg","datePublished":"2024-04-09T16:48:46+00:00","dateModified":"2025-03-27T13:02:56+00:00","description":"Durante el 2023, la facturaci\u00f3n de OcasionPlus incremento un 54% comparando con el a\u00f1o anterior. Este rendimiento se reflej\u00f3 en la venta de compactos.","breadcrumb":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/facturacion-ocasionplus-2023\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ocasionplus.com\/noticias\/facturacion-ocasionplus-2023\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ocasionplus.com\/noticias\/facturacion-ocasionplus-2023\/#primaryimage","url":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/04\/IMG_0138-1-1.jpg","contentUrl":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/04\/IMG_0138-1-1.jpg","width":1280,"height":766,"caption":"OcasionPlus Getafe es una de las tiendas que m\u00e1s vende de la empresa"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ocasionplus.com\/noticias\/facturacion-ocasionplus-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ocasionplus.com\/"},{"@type":"ListItem","position":2,"name":"La facturaci\u00f3n de OcasionPlus en 2023"}]},{"@type":"WebSite","@id":"https:\/\/noticias.grupoocasionplus.com\/#website","url":"https:\/\/noticias.grupoocasionplus.com\/","name":"OcasionPlus Blog","description":"Veh\u00edculos de ocasi\u00f3n","publisher":{"@id":"https:\/\/noticias.grupoocasionplus.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticias.grupoocasionplus.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticias.grupoocasionplus.com\/#organization","name":"OcasionPlus","url":"https:\/\/noticias.grupoocasionplus.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticias.grupoocasionplus.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/05\/cropped-cropped-oplus-logo-blog.png","contentUrl":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/05\/cropped-cropped-oplus-logo-blog.png","width":360,"height":71,"caption":"OcasionPlus"},"image":{"@id":"https:\/\/noticias.grupoocasionplus.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ocasionplus","https:\/\/x.com\/ocasionplus","https:\/\/www.instagram.com\/ocasion_plus","https:\/\/www.youtube.com\/channel\/UCBiCAto61Lyu27CgI95wrYQ","https:\/\/www.tiktok.com\/@ocasionplus.com","https:\/\/es.linkedin.com\/company\/ocasionplus"]},{"@type":"Person","@id":"https:\/\/noticias.grupoocasionplus.com\/#\/schema\/person\/7ab10ae859759ef2622b28e83ba868eb","name":"OcasionPlus","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/07\/ocasionplus_avatar-96x96.jpg","url":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/07\/ocasionplus_avatar-96x96.jpg","contentUrl":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/07\/ocasionplus_avatar-96x96.jpg","caption":"OcasionPlus"}}]}},"jetpack_featured_media_url":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/04\/IMG_0138-1-1.jpg","_links":{"self":[{"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/posts\/10691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/comments?post=10691"}],"version-history":[{"count":1,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/posts\/10691\/revisions"}],"predecessor-version":[{"id":15221,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/posts\/10691\/revisions\/15221"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/media\/10693"}],"wp:attachment":[{"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/media?parent=10691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/categories?post=10691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/tags?post=10691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}