{"id":11051,"date":"2024-05-06T17:51:51","date_gmt":"2024-05-06T15:51:51","guid":{"rendered":"https:\/\/blog.ocasionplus.com\/?p=11051"},"modified":"2025-03-27T14:00:49","modified_gmt":"2025-03-27T13:00:49","slug":"el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre","status":"publish","type":"post","link":"https:\/\/www.ocasionplus.com\/noticias\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\/","title":{"rendered":"El nuevo Mercedes-AMG CLE 53: diversi\u00f3n al aire libre"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">El nuevo<strong> Mercedes-AMG CLE 53 4MATIC<\/strong> cabriolet dise\u00f1ado para vivir todas las emociones de <a href=\"https:\/\/www.ocasionplus.com\/coches-ocasion\/cabrio-descapotable\"><strong><mark class=\"has-inline-color has-vivid-cyan-blue-color\" style=\"background-color: rgba(0, 0, 0, 0);\">un deportivo con el techo convertible<\/mark><\/strong><mark class=\"has-inline-color has-vivid-cyan-blue-color\" style=\"background-color: rgba(0, 0, 0, 0);\">.<\/mark><\/a>\u00a0Este modelo <strong>equipa un motor de 6 cilindros en l\u00ednea<\/strong> y un equipamiento muy amplio de serie con todos los elementos necesarios de confort como el <strong>AIRCAP o el AIRSCARF<\/strong> para mejorar la refrigeraci\u00f3n y ventilaci\u00f3n a la altura de cuello en las cuatro plazas \u00fatiles. Un coche muy pr\u00e1ctico que seg\u00fan <a href=\"https:\/\/www.ocasionplus.com\/coches-ocasion\/mercedes\"><strong><mark class=\"has-inline-color has-vivid-cyan-blue-color\" style=\"background-color: rgba(0, 0, 0, 0);\">Mercedes<\/mark><\/strong><\/a> se puede utilizar en el d\u00eda a d\u00eda, realizar viajes y conducir de forma divertida en una carretera<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\"><strong>Motor de 6 cilindros y 449 caballos de potencia<\/strong><\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">El <strong>nuevo Mercedes-AMG CLE 53 4MATIC<\/strong> equipa un motor de 6 cilindros en l\u00ednea de 3,0 litros, con doble turbocompresor que desarrolla una <strong>potencia de 446 caballos<\/strong>. Adem\u00e1s, cuenta con un <strong>sistema h\u00edbrido de 48 voltios<\/strong> que ofrece 17 kW o 23 caballos adicionales de potencia y un par de 205 Nm, <strong>tracci\u00f3n a las cuatro ruedas<\/strong> AMG Performance 4MATIC+ y una direcci\u00f3n activa en el eje trasero.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Esto junto a una transmisi\u00f3n <strong>AMG SPEEDSHIFT TCT 9G<\/strong> que ofrece tiempos de cambio muy cortos, una respuesta r\u00e1pida, funci\u00f3n de doble embrague y m\u00faltiples cambios descendentes. <strong>Mercedes <\/strong>ofrece la elecci\u00f3n de <strong>hasta 5 programas de conducci\u00f3n<\/strong> que facilita la conducci\u00f3n, desde maniobras de aceleraci\u00f3n, hasta una conducci\u00f3n m\u00e1s suave y econ\u00f3mica que ahorra combustible. Gracias a las levas de cambio galvanizadas situadas detr\u00e1s del volante te permitir\u00e1n cambiar de forma manual el cambio.\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Adem\u00e1s, la velocidad m\u00e1xima del <strong>Mercedes-AMG CLE 53 4MATIC <\/strong>est\u00e1 limitada a 250 km\/h, que se puede aumentar hasta los 270 km\/h con <strong>el paquete AMG Driver<\/strong>. Para correr tambi\u00e9n se necesita frenar y este modelo equipa un sistema de frenos de alto rendimiento dise\u00f1ado por AMG con discos de frenos en la parte delantera perforados y autoventilados con pinzas fijas de 4 pistones, mientras que en la parte trasera cuenta con discos autoventilados con pinzas flotantes de un solo pist\u00f3n.\u00a0<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" class=\"wp-image-11053\" src=\"https:\/\/127.0.0.1\/wp-content\/uploads\/2024\/05\/24C0061_006-min-1024x683.jpg\" alt=\"Zaga del Mercedes CLE 53 4MATIC\" \/>\r\n<figcaption class=\"wp-element-caption\">Zaga del Mercedes CLE 53 4MATIC<\/figcaption>\r\n<\/figure>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\"><strong>Dise\u00f1o interior y equipamiento AMG<\/strong><\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">El <strong>Mercedes-AMG CLE 53 4MATIC<\/strong> es un deportivo que no deja de lado la tecnolog\u00eda y las comodidades del conductor, como una pantalla de instrumentos totalmente digital de 12,3 pulgadas y una pantalla central de infoentretenimiento de 11,9 pulgadas en formato vertical. Asimismo, el conductor puede elegir entre los estilos de la pantalla Classic, Sport y SuperSport. Este \u00faltimo, solo disponible en la versi\u00f3n AMG con tac\u00f3metro central, indicadores horizontales, obtener datos del motor, visualizaci\u00f3n de la marcha, calentamiento, configurador, medidor G y cronometro de carrera.\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Adem\u00e1s, el interior del cabrio equipa <strong>una iluminaci\u00f3n ambiental<\/strong> <strong>din\u00e1mica <\/strong>opcional con 64 colores, con franjas de luz que se extienden por a trav\u00e9s de las puertas hasta los asientos traseros. Los asientos de cuero tienen revestimiento especial que refleja los rayos del sol y evita el sobrecalentamiento. Incluso con el techo cerrado el interior se calienta menos gracias al material de construcci\u00f3n de los asientos.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">El <strong>Mercedes-AMG CLE 53 4MATIC<\/strong> cuenta con una capota de tela, con un dise\u00f1o multicapa, que aporta un gran aislamiento que permite conducir durante todo el a\u00f1o. Adem\u00e1s, reduce el ruido y el viento para una conducci\u00f3n m\u00e1s c\u00f3moda. Esta capota se puede abrir o cerrar en tan solo 20 segundos mientras la conducci\u00f3n sea menor de 60 km\/h y tiene un funcionamiento totalmente el\u00e9ctrico. Este techo est\u00e1 disponible en rojo, negro y gris.<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" class=\"wp-image-11054\" src=\"https:\/\/127.0.0.1\/wp-content\/uploads\/2024\/05\/24C0061_025-min-1024x683.jpg\" alt=\"Interior del Mercedes CLE 53 4MATIC\" \/>\r\n<figcaption class=\"wp-element-caption\">Interior del Mercedes CLE 53 4MATIC<\/figcaption>\r\n<\/figure>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">A pesar de ser un coche deportivo y cabrio, tiene <strong>un maletero de grandes dimensiones con un volumen de 385 litros<\/strong> y con el techo abierto se reduce hasta los 295 litros y su capacidad se puede ampliar si se abaten los asientos traseros.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">El sistema <strong>KEYLESS-GO<\/strong> de serie permite acceder al veh\u00edculo sin utilizar la llave y permite bloquear y desbloquear las puertas tocando la manija.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">El<strong> Mercedes-AMG CLE 53 4MATIC<\/strong> ofrece <strong>la \u00faltima tecnolog\u00eda en seguridad para los ocupantes <\/strong>con un sistema de protecci\u00f3n contra vuelcos en combinaci\u00f3n con los pilares A r\u00edgidos, creando un espacio interior de supervivencia. Adem\u00e1s, cuenta con sistemas de retenci\u00f3n al asiento en caso de accidente y 11 airbags que forman un amplio equipamiento de serie.<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>El nuevo Mercedes-AMG CLE 53 4MATIC cabriolet dise\u00f1ado para vivir todas las emociones de un deportivo con el techo convertible.<\/p>\n","protected":false},"author":2,"featured_media":11055,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[373],"class_list":["post-11051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias","tag-mercedes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.8 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El nuevo Mercedes-AMG CLE 53: diversi\u00f3n al aire libre - OcasionPlus Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ocasionplus.com\/noticias\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El nuevo Mercedes-AMG CLE 53: diversi\u00f3n al aire libre\" \/>\n<meta property=\"og:description\" content=\"El nuevo Mercedes-AMG CLE 53 4MATIC cabriolet dise\u00f1ado para vivir todas las emociones de un deportivo con el techo convertible.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ocasionplus.com\/noticias\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\/\" \/>\n<meta property=\"og:site_name\" content=\"OcasionPlus Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ocasionplus\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-06T15:51:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-27T13:00:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/05\/24C0061_004-min-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"OcasionPlus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ocasionplus\" \/>\n<meta name=\"twitter:site\" content=\"@ocasionplus\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"OcasionPlus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\\\/\"},\"author\":{\"name\":\"OcasionPlus\",\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#\\\/schema\\\/person\\\/7ab10ae859759ef2622b28e83ba868eb\"},\"headline\":\"El nuevo Mercedes-AMG CLE 53: diversi\u00f3n al aire libre\",\"datePublished\":\"2024-05-06T15:51:51+00:00\",\"dateModified\":\"2025-03-27T13:00:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\\\/\"},\"wordCount\":727,\"publisher\":{\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/24C0061_004-min-scaled-1.jpg\",\"keywords\":[\"mercedes\"],\"articleSection\":[\"\u00daltimas Noticias\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\\\/\",\"url\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\\\/\",\"name\":\"El nuevo Mercedes-AMG CLE 53: diversi\u00f3n al aire libre - OcasionPlus Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/24C0061_004-min-scaled-1.jpg\",\"datePublished\":\"2024-05-06T15:51:51+00:00\",\"dateModified\":\"2025-03-27T13:00:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/24C0061_004-min-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/24C0061_004-min-scaled-1.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Mercedes CLE 53 4MATIC\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ocasionplus.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El nuevo Mercedes-AMG CLE 53: diversi\u00f3n al aire libre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#website\",\"url\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/\",\"name\":\"OcasionPlus Blog\",\"description\":\"Veh\u00edculos de ocasi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#organization\",\"name\":\"OcasionPlus\",\"url\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-cropped-oplus-logo-blog.png\",\"contentUrl\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-cropped-oplus-logo-blog.png\",\"width\":360,\"height\":71,\"caption\":\"OcasionPlus\"},\"image\":{\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ocasionplus\",\"https:\\\/\\\/x.com\\\/ocasionplus\",\"https:\\\/\\\/www.instagram.com\\\/ocasion_plus\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCBiCAto61Lyu27CgI95wrYQ\",\"https:\\\/\\\/www.tiktok.com\\\/@ocasionplus.com\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/ocasionplus\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#\\\/schema\\\/person\\\/7ab10ae859759ef2622b28e83ba868eb\",\"name\":\"OcasionPlus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/ocasionplus_avatar-96x96.jpg\",\"url\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/ocasionplus_avatar-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/ocasionplus_avatar-96x96.jpg\",\"caption\":\"OcasionPlus\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El nuevo Mercedes-AMG CLE 53: diversi\u00f3n al aire libre - OcasionPlus Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ocasionplus.com\/noticias\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\/","og_locale":"es_ES","og_type":"article","og_title":"El nuevo Mercedes-AMG CLE 53: diversi\u00f3n al aire libre","og_description":"El nuevo Mercedes-AMG CLE 53 4MATIC cabriolet dise\u00f1ado para vivir todas las emociones de un deportivo con el techo convertible.","og_url":"https:\/\/www.ocasionplus.com\/noticias\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\/","og_site_name":"OcasionPlus Blog","article_publisher":"https:\/\/www.facebook.com\/ocasionplus","article_published_time":"2024-05-06T15:51:51+00:00","article_modified_time":"2025-03-27T13:00:49+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/05\/24C0061_004-min-scaled-1.jpg","type":"image\/jpeg"}],"author":"OcasionPlus","twitter_card":"summary_large_image","twitter_creator":"@ocasionplus","twitter_site":"@ocasionplus","twitter_misc":{"Escrito por":"OcasionPlus","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ocasionplus.com\/noticias\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\/#article","isPartOf":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\/"},"author":{"name":"OcasionPlus","@id":"https:\/\/noticias.grupoocasionplus.com\/#\/schema\/person\/7ab10ae859759ef2622b28e83ba868eb"},"headline":"El nuevo Mercedes-AMG CLE 53: diversi\u00f3n al aire libre","datePublished":"2024-05-06T15:51:51+00:00","dateModified":"2025-03-27T13:00:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\/"},"wordCount":727,"publisher":{"@id":"https:\/\/noticias.grupoocasionplus.com\/#organization"},"image":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/05\/24C0061_004-min-scaled-1.jpg","keywords":["mercedes"],"articleSection":["\u00daltimas Noticias"],"inLanguage":"es","copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.ocasionplus.com\/noticias\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\/","url":"https:\/\/www.ocasionplus.com\/noticias\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\/","name":"El nuevo Mercedes-AMG CLE 53: diversi\u00f3n al aire libre - OcasionPlus Blog","isPartOf":{"@id":"https:\/\/noticias.grupoocasionplus.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\/#primaryimage"},"image":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/05\/24C0061_004-min-scaled-1.jpg","datePublished":"2024-05-06T15:51:51+00:00","dateModified":"2025-03-27T13:00:49+00:00","breadcrumb":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ocasionplus.com\/noticias\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ocasionplus.com\/noticias\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\/#primaryimage","url":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/05\/24C0061_004-min-scaled-1.jpg","contentUrl":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/05\/24C0061_004-min-scaled-1.jpg","width":2560,"height":1707,"caption":"Mercedes CLE 53 4MATIC"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ocasionplus.com\/noticias\/el-nuevo-mercedes-amg-cle-53-diversion-al-aire-libre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ocasionplus.com\/"},{"@type":"ListItem","position":2,"name":"El nuevo Mercedes-AMG CLE 53: diversi\u00f3n al aire libre"}]},{"@type":"WebSite","@id":"https:\/\/noticias.grupoocasionplus.com\/#website","url":"https:\/\/noticias.grupoocasionplus.com\/","name":"OcasionPlus Blog","description":"Veh\u00edculos de ocasi\u00f3n","publisher":{"@id":"https:\/\/noticias.grupoocasionplus.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticias.grupoocasionplus.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticias.grupoocasionplus.com\/#organization","name":"OcasionPlus","url":"https:\/\/noticias.grupoocasionplus.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticias.grupoocasionplus.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/05\/cropped-cropped-oplus-logo-blog.png","contentUrl":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/05\/cropped-cropped-oplus-logo-blog.png","width":360,"height":71,"caption":"OcasionPlus"},"image":{"@id":"https:\/\/noticias.grupoocasionplus.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ocasionplus","https:\/\/x.com\/ocasionplus","https:\/\/www.instagram.com\/ocasion_plus","https:\/\/www.youtube.com\/channel\/UCBiCAto61Lyu27CgI95wrYQ","https:\/\/www.tiktok.com\/@ocasionplus.com","https:\/\/es.linkedin.com\/company\/ocasionplus"]},{"@type":"Person","@id":"https:\/\/noticias.grupoocasionplus.com\/#\/schema\/person\/7ab10ae859759ef2622b28e83ba868eb","name":"OcasionPlus","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/07\/ocasionplus_avatar-96x96.jpg","url":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/07\/ocasionplus_avatar-96x96.jpg","contentUrl":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/07\/ocasionplus_avatar-96x96.jpg","caption":"OcasionPlus"}}]}},"jetpack_featured_media_url":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/05\/24C0061_004-min-scaled-1.jpg","_links":{"self":[{"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/posts\/11051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/comments?post=11051"}],"version-history":[{"count":1,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/posts\/11051\/revisions"}],"predecessor-version":[{"id":11377,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/posts\/11051\/revisions\/11377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/media\/11055"}],"wp:attachment":[{"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/media?parent=11051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/categories?post=11051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/tags?post=11051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}