{"id":1161,"date":"2014-01-22T12:02:56","date_gmt":"2014-01-22T12:02:56","guid":{"rendered":"https:\/\/blog.ocasionplus.com\/?p=1161"},"modified":"2025-03-27T16:13:57","modified_gmt":"2025-03-27T15:13:57","slug":"precio-medio-coches-segunda-mano","status":"publish","type":"post","link":"https:\/\/www.ocasionplus.com\/noticias\/precio-medio-coches-segunda-mano\/","title":{"rendered":"El precio medio de los coches de segunda mano se situ\u00f3 en los 10.443 euros en 2013"},"content":{"rendered":"<p>Un \u00faltimo informe nos muestra datos de gran inter\u00e9s en el <a title=\"Ocasi\u00f3n Plus, coches de segunda mano en Madrid\" href=\"https:\/\/www.ocasionplus.com\/?from=blog\" target=\"_blank\" rel=\"noopener\"><strong>sector del veh\u00edculo de ocasi\u00f3n<\/strong><\/a> como el precio medio de venta, la antig\u00fcedad, kilometraje, el modelo m\u00e1s demandado y el importe medio y variaci\u00f3n respecto al a\u00f1o pasado en las diferentes comunidades aut\u00f3nomas.<\/p>\n<p>En general, en Espa\u00f1a, el <strong>precio medio del veh\u00edculo de ocasi\u00f3n<\/strong> se situ\u00f3 en 2013 en 10.443 euros, un 0,3% por encima del valor medio registrado en 2012, seg\u00fan Coches.net.<\/p>\n<p>Por un lado, la <strong>antig\u00fcedad media de los coches de segunda mano<\/strong> a la venta en Espa\u00f1a se situ\u00f3 en 2013 en los 103 meses (8 a\u00f1os y 7 meses), mientras que en 2012 la antig\u00fcedad media cerr\u00f3 pr\u00e1cticamente sin cambios, en los 102 (8 a\u00f1os y 6 meses).<\/p>\n<p>En cuanto al <strong>kilometraje<\/strong>, la oferta de <strong>coches de ocasi\u00f3n con m\u00e1s de 100.000 kil\u00f3metros<\/strong> alcanz\u00f3 un 46,4 % del total, lo que supone un incremento comparado con el 45,9% registrado en 2012.<\/p>\n<p><a href=\"https:\/\/blog.ocasionplus.com\/berlina-diesel-gris-manual-demandado\/\">El <strong>autom\u00f3vil de segunda mano m\u00e1s ofertado<\/strong> en 2013 fue el de tipo berlina (62,51%), con cambio manual (80,2%) y combustible di\u00e9sel (60,1%)<\/a>. Estos datos apenas demuestran variaci\u00f3n respecto a los de 2012, aunque s\u00ed es cierto que se aprecia un ligero aumento (del 0,3% al 0,4%) en la oferta de veh\u00edculos de ocasi\u00f3n con propulsi\u00f3n h\u00edbrida o el\u00e9ctrica.<\/p>\n<p>Los <strong>modelos de ocasi\u00f3n m\u00e1s ofertados en Espa\u00f1a<\/strong> durante el 2013 fueron el BMW Serie 3 (4%), el Renault Megane (2,9%) y el Volkswagen Golf (2,9%).<\/p>\n<p>En cuanto al <strong>precio medio del coche seminuevo en las diferentes Comunidades Aut\u00f3nomas<\/strong>, las que cerraron el a\u00f1o con un precio medio del usado m\u00e1s bajo fueron Canarias (8.843 euros), Galicia (8.990) y Comunidad Valenciana (9.230).<\/p>\n<p>Por el contrario, aquellas que en 2013 registraron un<strong> precio medio mayor para el veh\u00edculo usado<\/strong> son Madrid (11.762 euros), el Pa\u00eds Vasco (10.974) y Asturias (10.526).<\/p>\n<p>La mayor\u00eda de las Comunidades Aut\u00f3nomas cerraron 2013 con precios m\u00e1s altos respecto al a\u00f1o anterior, siendo las m\u00e1s destacadas Extremadura (+16,92%), Baleares (+15,26%) y Cantabria (+11,79%).<\/p>\n<p>Para terminar, las Comunidades Aut\u00f3nomas que mostraron una variaci\u00f3n a la baja m\u00e1s pronunciada fueron Canarias (-16,42%), Galicia (-9,92%) y la Comunidad Valenciana (-8,14%).<\/p>\n<p>Por cierto, en <strong>OcasionPlus por menos de estos precios tenemos modelos para todos los gustos y necesidades<\/strong>. Concretamente, si entras en nuestro <a title=\"Buscador de coches de ocasi\u00f3n\" href=\"https:\/\/www.ocasionplus.com\/coches-ocasion?from=blog\" target=\"_blank\" rel=\"noopener\"><strong>buscador de coches de ocasi\u00f3n<\/strong><\/a> y filtras por precio, disponemos de&#8230; \u00a1<strong>130 coches de segunda mano por menos de 10.000 euros<\/strong>!<\/p>\n<p>Elige el tuyo y <a title=\"Concesionario de coches de ocasi\u00f3n en Madrid\" href=\"https:\/\/www.ocasionplus.com\/contacto?from=blog\" target=\"_blank\" rel=\"noopener\"><strong>ven a probarlo a nuestras instalaciones<\/strong><\/a>.<\/p>\n<p>\u00a1Te esperamos!<\/p>\n<p style=\"text-align: right;\">Fuente:\u00a0Noticias EFE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En cuanto al precio medio del coche seminuevo en las diferentes Comunidades Aut\u00f3nomas, las que cerraron el a\u00f1o con un precio medio del usado m\u00e1s bajo fueron Canarias (8.843 euros), Galicia (8.990 euros) y la Comunidad Valenciana (9.230 euros).<\/p>\n","protected":false},"author":2,"featured_media":1165,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-1161","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consejos-practicos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.8 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El precio medio de los segunda mano se situ\u00f3 en 10.443 euros en 2013<\/title>\n<meta name=\"description\" content=\"Un \u00faltimo informe nos muestra datos de gran inter\u00e9s en el sector del veh\u00edculo de ocasi\u00f3n como el precio medio de venta, la antig\u00fcedad o el kilometraje.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ocasionplus.com\/noticias\/precio-medio-coches-segunda-mano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El precio medio de los coches de segunda mano se situ\u00f3 en los 10.443 euros en 2013\" \/>\n<meta property=\"og:description\" content=\"Un \u00faltimo informe nos muestra datos de gran inter\u00e9s en el sector del veh\u00edculo de ocasi\u00f3n como el precio medio de venta, la antig\u00fcedad o el kilometraje.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ocasionplus.com\/noticias\/precio-medio-coches-segunda-mano\/\" \/>\n<meta property=\"og:site_name\" content=\"OcasionPlus Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ocasionplus\" \/>\n<meta property=\"article:published_time\" content=\"2014-01-22T12:02:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-27T15:13:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2014\/01\/precio-medio-coches-segunda-mano-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1681\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"OcasionPlus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ocasionplus\" \/>\n<meta name=\"twitter:site\" content=\"@ocasionplus\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"OcasionPlus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/precio-medio-coches-segunda-mano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/precio-medio-coches-segunda-mano\\\/\"},\"author\":{\"name\":\"OcasionPlus\",\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#\\\/schema\\\/person\\\/7ab10ae859759ef2622b28e83ba868eb\"},\"headline\":\"El precio medio de los coches de segunda mano se situ\u00f3 en los 10.443 euros en 2013\",\"datePublished\":\"2014-01-22T12:02:56+00:00\",\"dateModified\":\"2025-03-27T15:13:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/precio-medio-coches-segunda-mano\\\/\"},\"wordCount\":434,\"publisher\":{\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/precio-medio-coches-segunda-mano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/precio-medio-coches-segunda-mano-scaled.jpg\",\"articleSection\":[\"Consejos\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2014\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/precio-medio-coches-segunda-mano\\\/\",\"url\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/precio-medio-coches-segunda-mano\\\/\",\"name\":\"El precio medio de los segunda mano se situ\u00f3 en 10.443 euros en 2013\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/precio-medio-coches-segunda-mano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/precio-medio-coches-segunda-mano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/precio-medio-coches-segunda-mano-scaled.jpg\",\"datePublished\":\"2014-01-22T12:02:56+00:00\",\"dateModified\":\"2025-03-27T15:13:57+00:00\",\"description\":\"Un \u00faltimo informe nos muestra datos de gran inter\u00e9s en el sector del veh\u00edculo de ocasi\u00f3n como el precio medio de venta, la antig\u00fcedad o el kilometraje.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/precio-medio-coches-segunda-mano\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/precio-medio-coches-segunda-mano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/precio-medio-coches-segunda-mano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/precio-medio-coches-segunda-mano-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/precio-medio-coches-segunda-mano-scaled.jpg\",\"width\":2560,\"height\":1681,\"caption\":\"Precio medio coches segunda mano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/precio-medio-coches-segunda-mano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ocasionplus.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El precio medio de los coches de segunda mano se situ\u00f3 en los 10.443 euros en 2013\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#website\",\"url\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/\",\"name\":\"OcasionPlus Blog\",\"description\":\"Veh\u00edculos de ocasi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#organization\",\"name\":\"OcasionPlus\",\"url\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-cropped-oplus-logo-blog.png\",\"contentUrl\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-cropped-oplus-logo-blog.png\",\"width\":360,\"height\":71,\"caption\":\"OcasionPlus\"},\"image\":{\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ocasionplus\",\"https:\\\/\\\/x.com\\\/ocasionplus\",\"https:\\\/\\\/www.instagram.com\\\/ocasion_plus\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCBiCAto61Lyu27CgI95wrYQ\",\"https:\\\/\\\/www.tiktok.com\\\/@ocasionplus.com\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/ocasionplus\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#\\\/schema\\\/person\\\/7ab10ae859759ef2622b28e83ba868eb\",\"name\":\"OcasionPlus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/ocasionplus_avatar-96x96.jpg\",\"url\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/ocasionplus_avatar-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/ocasionplus_avatar-96x96.jpg\",\"caption\":\"OcasionPlus\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El precio medio de los segunda mano se situ\u00f3 en 10.443 euros en 2013","description":"Un \u00faltimo informe nos muestra datos de gran inter\u00e9s en el sector del veh\u00edculo de ocasi\u00f3n como el precio medio de venta, la antig\u00fcedad o el kilometraje.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ocasionplus.com\/noticias\/precio-medio-coches-segunda-mano\/","og_locale":"es_ES","og_type":"article","og_title":"El precio medio de los coches de segunda mano se situ\u00f3 en los 10.443 euros en 2013","og_description":"Un \u00faltimo informe nos muestra datos de gran inter\u00e9s en el sector del veh\u00edculo de ocasi\u00f3n como el precio medio de venta, la antig\u00fcedad o el kilometraje.","og_url":"https:\/\/www.ocasionplus.com\/noticias\/precio-medio-coches-segunda-mano\/","og_site_name":"OcasionPlus Blog","article_publisher":"https:\/\/www.facebook.com\/ocasionplus","article_published_time":"2014-01-22T12:02:56+00:00","article_modified_time":"2025-03-27T15:13:57+00:00","og_image":[{"width":2560,"height":1681,"url":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2014\/01\/precio-medio-coches-segunda-mano-scaled.jpg","type":"image\/jpeg"}],"author":"OcasionPlus","twitter_card":"summary_large_image","twitter_creator":"@ocasionplus","twitter_site":"@ocasionplus","twitter_misc":{"Escrito por":"OcasionPlus","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ocasionplus.com\/noticias\/precio-medio-coches-segunda-mano\/#article","isPartOf":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/precio-medio-coches-segunda-mano\/"},"author":{"name":"OcasionPlus","@id":"https:\/\/noticias.grupoocasionplus.com\/#\/schema\/person\/7ab10ae859759ef2622b28e83ba868eb"},"headline":"El precio medio de los coches de segunda mano se situ\u00f3 en los 10.443 euros en 2013","datePublished":"2014-01-22T12:02:56+00:00","dateModified":"2025-03-27T15:13:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/precio-medio-coches-segunda-mano\/"},"wordCount":434,"publisher":{"@id":"https:\/\/noticias.grupoocasionplus.com\/#organization"},"image":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/precio-medio-coches-segunda-mano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2014\/01\/precio-medio-coches-segunda-mano-scaled.jpg","articleSection":["Consejos"],"inLanguage":"es","copyrightYear":"2014","copyrightHolder":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.ocasionplus.com\/noticias\/precio-medio-coches-segunda-mano\/","url":"https:\/\/www.ocasionplus.com\/noticias\/precio-medio-coches-segunda-mano\/","name":"El precio medio de los segunda mano se situ\u00f3 en 10.443 euros en 2013","isPartOf":{"@id":"https:\/\/noticias.grupoocasionplus.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/precio-medio-coches-segunda-mano\/#primaryimage"},"image":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/precio-medio-coches-segunda-mano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2014\/01\/precio-medio-coches-segunda-mano-scaled.jpg","datePublished":"2014-01-22T12:02:56+00:00","dateModified":"2025-03-27T15:13:57+00:00","description":"Un \u00faltimo informe nos muestra datos de gran inter\u00e9s en el sector del veh\u00edculo de ocasi\u00f3n como el precio medio de venta, la antig\u00fcedad o el kilometraje.","breadcrumb":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/precio-medio-coches-segunda-mano\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ocasionplus.com\/noticias\/precio-medio-coches-segunda-mano\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ocasionplus.com\/noticias\/precio-medio-coches-segunda-mano\/#primaryimage","url":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2014\/01\/precio-medio-coches-segunda-mano-scaled.jpg","contentUrl":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2014\/01\/precio-medio-coches-segunda-mano-scaled.jpg","width":2560,"height":1681,"caption":"Precio medio coches segunda mano"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ocasionplus.com\/noticias\/precio-medio-coches-segunda-mano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ocasionplus.com\/"},{"@type":"ListItem","position":2,"name":"El precio medio de los coches de segunda mano se situ\u00f3 en los 10.443 euros en 2013"}]},{"@type":"WebSite","@id":"https:\/\/noticias.grupoocasionplus.com\/#website","url":"https:\/\/noticias.grupoocasionplus.com\/","name":"OcasionPlus Blog","description":"Veh\u00edculos de ocasi\u00f3n","publisher":{"@id":"https:\/\/noticias.grupoocasionplus.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticias.grupoocasionplus.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticias.grupoocasionplus.com\/#organization","name":"OcasionPlus","url":"https:\/\/noticias.grupoocasionplus.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticias.grupoocasionplus.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/05\/cropped-cropped-oplus-logo-blog.png","contentUrl":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/05\/cropped-cropped-oplus-logo-blog.png","width":360,"height":71,"caption":"OcasionPlus"},"image":{"@id":"https:\/\/noticias.grupoocasionplus.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ocasionplus","https:\/\/x.com\/ocasionplus","https:\/\/www.instagram.com\/ocasion_plus","https:\/\/www.youtube.com\/channel\/UCBiCAto61Lyu27CgI95wrYQ","https:\/\/www.tiktok.com\/@ocasionplus.com","https:\/\/es.linkedin.com\/company\/ocasionplus"]},{"@type":"Person","@id":"https:\/\/noticias.grupoocasionplus.com\/#\/schema\/person\/7ab10ae859759ef2622b28e83ba868eb","name":"OcasionPlus","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/07\/ocasionplus_avatar-96x96.jpg","url":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/07\/ocasionplus_avatar-96x96.jpg","contentUrl":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/07\/ocasionplus_avatar-96x96.jpg","caption":"OcasionPlus"}}]}},"jetpack_featured_media_url":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2014\/01\/precio-medio-coches-segunda-mano-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/posts\/1161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/comments?post=1161"}],"version-history":[{"count":1,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/posts\/1161\/revisions"}],"predecessor-version":[{"id":15553,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/posts\/1161\/revisions\/15553"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/media\/1165"}],"wp:attachment":[{"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/media?parent=1161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/categories?post=1161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/tags?post=1161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}