{"id":14873,"date":"2025-01-20T14:08:34","date_gmt":"2025-01-20T13:08:34","guid":{"rendered":"https:\/\/www.ocasionplus.com\/noticias\/?p=14873"},"modified":"2025-03-27T10:07:47","modified_gmt":"2025-03-27T09:07:47","slug":"volkswagen-id3-segunda-mano","status":"publish","type":"post","link":"https:\/\/www.ocasionplus.com\/noticias\/volkswagen-id3-segunda-mano\/","title":{"rendered":"Volkswagen ID3 segunda mano: Referente el\u00e9ctrico de ocasi\u00f3n"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]<span data-contrast=\"auto\"><strong>El Volkswagen ID3 de segunda mano fue el modelo que marc\u00f3 el inicio de una nueva era para Volkswagen<\/strong>, siendo el primer miembro de su familia ID, enfocada exclusivamente en la electrificaci\u00f3n. Pese a que la historia de este exitoso modelo no est\u00e1 exenta de altibajos, desde sus innovadoras propuestas iniciales y pasando por los diversos retos a los que ha tenido que hacer frente tras su lanzamiento, hoy el VW ID3 es una gran opci\u00f3n el\u00e9ctrica para quien busca un veh\u00edculo de ocasi\u00f3n.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\"><strong>En el mercado de coches de ocasi\u00f3n, el Volkswagen ID3 ha ido ganando una gran popularidad gracias a sus m\u00faltiples configuraciones y a una notable autonom\u00eda<\/strong>. Si tienes en mente adquirir uno de ellos y pasarte a la movilidad el\u00e9ctrica, adquirir un ID3 de segunda mano puede ser una decisi\u00f3n inteligente y econ\u00f3mica. Su dise\u00f1o moderno, sus avanzadas prestaciones tecnol\u00f3gicas y su orientaci\u00f3n a la eficiencia energ\u00e9tica lo han convertido -y siguen haci\u00e9ndolo tiempo despu\u00e9s de su presentaci\u00f3n al mercado- en una gran opci\u00f3n en el mercado de coches de ocasi\u00f3n. Si est\u00e1s considerando dar el salto a la movilidad el\u00e9ctrica, el ID3 es un modelo que re\u00fane todas las caracter\u00edsticas necesarias para disfrutar de una experiencia de conducci\u00f3n innovadora y m\u00e1s respetuosa con el medio ambiente.\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<h2><b><span data-contrast=\"auto\">\u00bfComprar Volkswagen ID3 de segunda mano? As\u00ed ha evolucionado el modelo:<\/span><\/b><span data-ccp-props=\"{}\">\u00a0<\/span><\/h2>\n<p><span data-contrast=\"auto\">La presentaci\u00f3n oficial del Volkswagen ID3 tuvo lugar en el Auto Show de Frankfurt en septiembre de 2019, aunque con anterioridad ya se hab\u00edan presentado ciertos anticipos de su dise\u00f1o como el concepto I.D. en 2016. <strong>El modelo represent\u00f3 un cambio radical en la estrategia de Volkswagen<\/strong> con la promesa de ofrecer un coche el\u00e9ctrico accesible y sostenible para el p\u00fablico masivo.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Aun as\u00ed, el lanzamiento del VW ID3 coincidi\u00f3 con varios desaf\u00edos globales importantes. La pandemia de COVID-19, las crisis de suministro de componentes y ciertos problemas internos en el desarrollo de software afectaron a su producci\u00f3n inicial, generando retrasos en las entregas. A pesar de estos desaf\u00edos,<strong> las primeras unidades comenzaron a llegar a los clientes en Alemania en septiembre de 2020, y el modelo logr\u00f3 entregar cerca de 57.000 unidades durante ese a\u00f1o.<\/strong><\/span><strong>\u00a0<\/strong><\/p>\n<p><span data-contrast=\"auto\">El Volkswagen ID3 supuso un paso importante para la electrificaci\u00f3n de Volkswagen, adem\u00e1s de ser uno de los modelos que marcaron el comienzo de una nueva etapa para la industria de automoci\u00f3n en general. A pesar de algunas cr\u00edticas iniciales, relativas por ejemplo a la calidad del interior y al elevado precio del modelo, Volkswagen continu\u00f3 trabajado para mejorarlo con diversas actualizaciones que han ido llegando a los concesionarios, especialmente en con el<strong> restyling sometido en 2023 al VW ID3<\/strong>.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<h2><b><span data-contrast=\"auto\">Principales caracter\u00edsticas t\u00e9cnicas del Volkswagen ID3 de segunda mano <\/span><\/b><span data-ccp-props=\"{}\">\u00a0<\/span><\/h2>\n<p><span data-contrast=\"auto\">El Volkswagen ID3 es un coche compacto del <a href=\"https:\/\/www.ocasionplus.com\/coches-segunda-mano\/c\">segmento C<\/a>, dise\u00f1ado para ofrecer una experiencia equilibrada entre rendimiento y sostenibilidad. Adem\u00e1s, est\u00e1 basado en la plataforma MEB del Grupo Volkswagen, la cual est\u00e1 dise\u00f1ada espec\u00edficamente para veh\u00edculos el\u00e9ctricos.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<h3><b><span data-contrast=\"auto\">Algunas de las especificaciones m\u00e1s importantes del ID3 incluyen:<\/span><\/b><span data-ccp-props=\"{}\">\u00a0<\/span><\/h3>\n<ol>\n<li><b><span data-contrast=\"auto\"> Dimensiones<\/span><\/b><span data-contrast=\"auto\">: 4,26 metros de largo, 1,81 metros de ancho y 1,56 metros de alto, con una distancia entre ejes de 2,77 metros.<\/span><\/li>\n<li><b><span data-contrast=\"auto\"> Motorizaci\u00f3n<\/span><\/b><span data-contrast=\"auto\">: motor el\u00e9ctrico s\u00edncrono de im\u00e1n permanente ubicado en el eje trasero. La potencia var\u00eda entre 148 CV y 204 CV, dependiendo de la versi\u00f3n.<\/span><\/li>\n<li><b><span data-contrast=\"auto\"> Autonom\u00eda<\/span><\/b><span data-contrast=\"auto\">: bater\u00edas de 45, 58 o 77 kWh que ofrecen entre 330 km y 550 km seg\u00fan el ciclo WLTP.<\/span><\/li>\n<li><b><span data-contrast=\"auto\"> Carga<\/span><\/b><span data-contrast=\"auto\">: capacidad de carga r\u00e1pida CCS que permite recuperar hasta el 80% de la bater\u00eda en solo 30 minutos con una potencia de 100 kW.<\/span><\/li>\n<li><b><span data-contrast=\"auto\"> Capacidad de carga del maletero<\/span><\/b><span data-contrast=\"auto\">: 385 litros ampliables hasta 1.267 si los los asientos traseros est\u00e1n abatidos.<\/span><\/li>\n<\/ol>\n<p><span data-contrast=\"auto\">Adem\u00e1s, el dise\u00f1o aerodin\u00e1mico del que disfrutar\u00e1s al adquirir un Volkswagen ID3 de segunda mano, con un coeficiente de arrastre de 0,267, y una distribuci\u00f3n de peso optimizada gracias a la bater\u00eda ubicada en el suelo, aseguran una conducci\u00f3n muy estable y eficiente tanto en ciudad como en carretera.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<h2><b><span data-contrast=\"auto\">\u00bfC\u00f3mo es el interior y la tecnolog\u00eda que ofrece un Volkswagen ID3 de segunda mano?<\/span><\/b><span data-ccp-props=\"{}\">\u00a0<\/span><\/h2>\n<p><span data-contrast=\"auto\">El Volkswagen ID3 es reconocible, sobre todo, por su<strong> interior minimalista y moderno<\/strong>, dise\u00f1ado para maximizar la funcionalidad y el confort del conductor y los pasajeros. A pesar de su enfoque en la sostenibilidad, este modelo de la marca alemana no renuncia ni a la calidad ni a la tecnolog\u00eda.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">El habit\u00e1culo, por ejemplo, incluye <strong>materiales reciclados<\/strong>, como el tapizado de microfibra <\/span><i><span data-contrast=\"auto\">Artvelours Eco<\/span><\/i><span data-contrast=\"auto\"> en ciertas versiones, que contiene hasta un 71% de materiales reciclados, una apuesta que busca, precisamente, reflejar el compromiso de Volkswagen con la reducci\u00f3n del impacto ambiental.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<h3>Tecnolog\u00eda del Volkswagen ID3 de segunda mano<\/h3>\n<p><span data-contrast=\"auto\">Si hablamos de la <strong>cabina<\/strong>, \u00e9sta es <strong>completamente digital<\/strong>, con una pantalla t\u00e1ctil central de 10 pulgadas en los modelos iniciales, y que crece hasta las 12 pulgadas en versiones m\u00e1s recientes, y un sistema de infoentretenimiento que incluye conectividad con diferentes sistemas y dispositivos m\u00f3viles, as\u00ed como un planificador de rutas inteligente que optimiza el consumo de energ\u00eda y las paradas de recarga.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Otro punto destacado es la <strong>opci\u00f3n de disponer en algunas versiones de un Head-Up Display con realidad aumentada<\/strong>, el cual proyecta informaci\u00f3n relevante directamente en el parabrisas para facilitar una experiencia de conducci\u00f3n m\u00e1s intuitiva y segura.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">El VW ID3 tambi\u00e9n incorpora una amplia gama de sistemas de asistencia a la conducci\u00f3n pensados para conferirle un plus de seguridad y de comodidad en carretera como son:\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<ul>\n<li data-leveltext=\"-\" data-font=\"Aptos\" data-listid=\"5\" data-list-defn-props=\"{&quot;335551671&quot;:5,&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Aptos&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;-&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"5\" data-aria-level=\"1\"><b><span data-contrast=\"auto\">Travel Assist<\/span><\/b><span data-contrast=\"auto\">: es un sistema de conducci\u00f3n semiaut\u00f3noma que utiliza datos almacenados en la nube para realizar funciones como el cambio de carril autom\u00e1tico.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"-\" data-font=\"Aptos\" data-listid=\"5\" data-list-defn-props=\"{&quot;335551671&quot;:5,&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Aptos&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;-&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"6\" data-aria-level=\"1\"><b><span data-contrast=\"auto\">Park Assist Plus:<\/span><\/b><span data-contrast=\"auto\"> permite replicar maniobras de estacionamiento previamente realizadas y facilitar de este modo el aparcamiento en espacios reducidos.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"-\" data-font=\"Aptos\" data-listid=\"5\" data-list-defn-props=\"{&quot;335551671&quot;:5,&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Aptos&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;-&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"7\" data-aria-level=\"1\"><b><span data-contrast=\"auto\">Freno regenerativo<\/span><\/b><span data-contrast=\"auto\">: el motor el\u00e9ctrico act\u00faa como generador durante la frenada, recuperando energ\u00eda cin\u00e9tica para cargar la bater\u00eda y reduciendo el desgaste de los frenos. Adem\u00e1s, el modelo cuenta con un radio de giro de solo 10,2 metros, lo que lo hace muy \u00e1gil, f\u00e1cil de conducir y pr\u00e1ctico en los entornos urbanos.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<\/ul>\n<h2><b><span data-contrast=\"auto\">\u00bfC\u00f3mo es el dise\u00f1o exterior y la aerodin\u00e1mica del Volkswagen ID3?<\/span><\/b><span data-ccp-props=\"{}\">\u00a0<\/span><\/h2>\n<p><span data-contrast=\"auto\"><strong>El dise\u00f1o exterior del Volkswagen ID3 une modernidad y funcionalidad<\/strong>. Su est\u00e9tica es limpia y futurista, con detalles como faros LED de serie y una parrilla cerrada que enfatiza su car\u00e1cter el\u00e9ctrico.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\"><strong>En versiones recientes, el ID3 ha recibido un restyling<\/strong> que incluye un paragolpes m\u00e1s agresivo, luces traseras completamente iluminadas y mejoras aerodin\u00e1micas que reducen el coeficiente de arrastre a 0,263, unos cambios que mejoran tanto su apariencia como su eficiencia energ\u00e9tica.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<h2><b><span data-contrast=\"auto\">\u00bfQu\u00e9 motores y versiones tiene el Volkswagen ID3 de segunda mano?<\/span><\/b><span data-ccp-props=\"{}\">\u00a0<\/span><\/h2>\n<p><span data-contrast=\"auto\"><strong>El Volkswagen ID3 tiene varias configuraciones que cubren diferentes necesidades de los usuarios.<\/strong> Entre las opciones m\u00e1s destacadas que puedes encontrar en el mercado de ocasi\u00f3n se encuentran:<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"4\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><b><span data-contrast=\"auto\">Volkswagen ID.3 Pure<\/span><\/b><span data-contrast=\"auto\">: es la versi\u00f3n m\u00e1s b\u00e1sica de este el\u00e9ctrico, ideal para conductores urbanos, con una bater\u00eda de 45 kWh y una autonom\u00eda de hasta 330 kil\u00f3metros.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"4\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><b><span data-contrast=\"auto\">Volkswagen ID.3 Pro<\/span><\/b><span data-contrast=\"auto\">: ofrece un gran equilibrio entre precio y rendimiento, con una bater\u00eda de 58 kWh que ofrece una autonom\u00eda de 420 kil\u00f3metros.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"4\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"3\" data-aria-level=\"1\"><b><span data-contrast=\"auto\">Volkswagen ID.3 Pro S<\/span><\/b><span data-contrast=\"auto\">: esta versi\u00f3n fue dise\u00f1ada para viajes largos e incluye una bater\u00eda de 77 kWh con hasta 550 kil\u00f3metros de autonom\u00eda.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"4\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"4\" data-aria-level=\"1\"><b><span data-contrast=\"auto\">Volkswagen ID.3 GTX<\/span><\/b><span data-contrast=\"auto\">: el modelo deportivo, lanzado en 2024, con una potencia de hasta 326 CV y tracci\u00f3n integral, es una gran opci\u00f3n para los amantes de las m\u00e1s altas prestaciones.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<\/ul>\n<p><span data-contrast=\"auto\">Todas estas variantes permiten encontrar un Volkswagen ID3 de segunda mano que\u00a0 se adapte tanto a conductores que buscan eficiencia en su d\u00eda a d\u00eda como a aquellos interesados en el rendimiento y la autonom\u00eda para viajes m\u00e1s largos y prolongados.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<h2><b><span data-contrast=\"auto\">Qu\u00e9 tener en cuenta al comprar un VW ID3 de segunda mano. Comparaci\u00f3n con otros el\u00e9ctricos de ocasi\u00f3n<\/span><\/b><span data-ccp-props=\"{}\">\u00a0<\/span><\/h2>\n<p><span data-contrast=\"auto\">Si \u00faltimamente se te ha pasado por la cabeza comprar un Volkswagen ID3 de segunda mano, <a href=\"https:\/\/www.ocasionplus.com\/\">OcasionPlus<\/a> es la mejor opci\u00f3n para garantizar una compra segura y satisfactoria.<strong> Lo primero que debes tener en cuenta<\/strong>, si est\u00e1s pensando en comprar un veh\u00edculo el\u00e9ctrico, <strong>es el estado de la bater\u00eda<\/strong>, pero no es lo \u00fanico. En OcasionPlus, todos nuestros coches pasan por un proceso exhaustivo de revisi\u00f3n t\u00e9cnica que garantiza su estado. Adem\u00e1s, el certificado Carfax de cada veh\u00edculo que te ofrecemos te permitir\u00e1 conocer desde los mantenimientos realizados, el kilometraje o cualquier eventual da\u00f1o sufrido por el coche.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Adem\u00e1s, puedes realizar una prueba de conducci\u00f3n sin compromiso para evaluar el rendimiento del coche y asegurarte de que se adapta perfectamente a tus necesidades.<\/span><\/p>\n<h3><span data-ccp-props=\"{}\">Otros coches del mercado de ocasi\u00f3n el\u00e9ctricos\u00a0<\/span><\/h3>\n<p><span data-contrast=\"auto\">El Volkswagen ID3 es un fuerte competidor de otros modelos el\u00e9ctricos disponibles en el mercado de segunda mano, como el <\/span><a href=\"https:\/\/www.ocasionplus.com\/coches-segunda-mano\/nissan\/leaf\"><b><span data-contrast=\"auto\">Nissan Leaf<\/span><\/b><\/a><span data-contrast=\"auto\">, el <\/span><a href=\"https:\/\/www.ocasionplus.com\/coches-segunda-mano\/renault\/zoe\"><b><span data-contrast=\"auto\">Renault Zoe<\/span><\/b><\/a><span data-contrast=\"auto\"> o incluso el <\/span><b><span data-contrast=\"auto\"><a href=\"https:\/\/www.ocasionplus.com\/coches-segunda-mano\/tesla\/model-3\">Tesla Model 3<\/a>.<\/span><\/b><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Mientras que el Nissan Leaf es reconocido por su fiabilidad y el Renault Zoe por su accesibilidad,<strong> el Volkswagen ID3 destaca<\/strong>, adem\u00e1s de por la fiabilidad y prestigio de la marca alemana,<strong> por su equilibrio entre tecnolog\u00eda, autonom\u00eda y dise\u00f1o<\/strong>.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<h2>\u00bfQu\u00e9 ofrece el <span data-contrast=\"auto\"><strong>Volkswagen ID3 de segunda mano respecto a sus competidores?<\/strong><\/span><\/h2>\n<p><span data-contrast=\"auto\">En comparaci\u00f3n con el Tesla Model 3, el ID3 ofrece un <strong>precio m\u00e1s accesible<\/strong> en el mercado de segunda mano que lo convierte en una gran opci\u00f3n para los conductores que buscan una experiencia premium sin necesidad de realizar un desembolso tan elevado.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><strong>Por otro lado, <\/strong><span data-contrast=\"auto\"><strong>conducir el Volkswagen ID3 es una experiencia \u00fanica que combina dinamismo y confort<\/strong>. Su motor el\u00e9ctrico proporciona una entrega instant\u00e1nea de par, perfecta para maniobras r\u00e1pidas en ciudad y una conducci\u00f3n fluida en carretera. Asimismo, la propia ubicaci\u00f3n de la bater\u00eda en el suelo asegura un centro de gravedad bajo.\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">En cuanto al <strong>mantenimiento<\/strong>, el ID3 destaca por su sencillez y comodidad para el propietario. Los frenos regenerativos reducen el desgaste de las pastillas y discos, mientras que la ausencia de un motor de combusti\u00f3n interna tradicional elimina, por ejemplo, la necesidad de cambios de aceite o reparaciones mec\u00e1nicas asociadas a algunos de los componentes y sistemas comunes en este tipo de veh\u00edculos con motores ICE (<\/span><i><span data-contrast=\"auto\">Internal Combustion Engine)<\/span><\/i><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<h2>Conclusi\u00f3n final del <span data-contrast=\"auto\"><strong>Volkswagen ID3 de segunda mano<\/strong><\/span><\/h2>\n<p><span data-contrast=\"auto\">En resumidas cuentas, el Volkswagen ID3 de segunda mano representa el compromiso de Volkswagen con la movilidad el\u00e9ctrica y es una compra segura para el comprador. S<strong>u dise\u00f1o futurista, combinado con su tecnolog\u00eda avanzada y su enfoque en la sostenibilidad, lo convierten en una opci\u00f3n atractiva<\/strong> en el mercado de coches segunda mano Volkswagen.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Adem\u00e1s, <strong>el restyling de 2023 ha mejorado aspectos importantes del modelo<\/strong>, como la calidad de los acabados interiores y la integraci\u00f3n de nuevas tecnolog\u00edas para afianzar su posici\u00f3n como uno de los mejores coches el\u00e9ctricos disponibles en la actualidad en el mercado de seminuevos.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]El Volkswagen ID3 de segunda mano fue el modelo que marc\u00f3 el inicio de una nueva era para Volkswagen, siendo el primer miembro de su familia ID, enfocada exclusivamente en la electrificaci\u00f3n. Pese a que la historia de este exitoso modelo no est\u00e1 exenta de altibajos, desde sus innovadoras propuestas iniciales y pasando por&#8230;<\/p>\n","protected":false},"author":2,"featured_media":14874,"comment_status":"closed","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-14873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consejos-practicos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.8 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Volkswagen ID3 segunda mano: Referente el\u00e9ctrico de ocasi\u00f3n - OcasionPlus Blog<\/title>\n<meta name=\"description\" content=\"El Volkswagen ID3 de segunda mano ha ido ganando una gran popularidad gracias a sus m\u00faltiples configuraciones y a una notable autonom\u00eda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ocasionplus.com\/noticias\/volkswagen-id3-segunda-mano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Volkswagen ID3 segunda mano: Referente el\u00e9ctrico de ocasi\u00f3n\" \/>\n<meta property=\"og:description\" content=\"El Volkswagen ID3 de segunda mano ha ido ganando una gran popularidad gracias a sus m\u00faltiples configuraciones y a una notable autonom\u00eda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ocasionplus.com\/noticias\/volkswagen-id3-segunda-mano\/\" \/>\n<meta property=\"og:site_name\" content=\"OcasionPlus Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ocasionplus\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-20T13:08:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-27T09:07:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2025\/01\/Volkswagen-ID.3-1110x577-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1110\" \/>\n\t<meta property=\"og:image:height\" content=\"577\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"OcasionPlus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ocasionplus\" \/>\n<meta name=\"twitter:site\" content=\"@ocasionplus\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"OcasionPlus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/volkswagen-id3-segunda-mano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/volkswagen-id3-segunda-mano\\\/\"},\"author\":{\"name\":\"OcasionPlus\",\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#\\\/schema\\\/person\\\/7ab10ae859759ef2622b28e83ba868eb\"},\"headline\":\"Volkswagen ID3 segunda mano: Referente el\u00e9ctrico de ocasi\u00f3n\",\"datePublished\":\"2025-01-20T13:08:34+00:00\",\"dateModified\":\"2025-03-27T09:07:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/volkswagen-id3-segunda-mano\\\/\"},\"wordCount\":1926,\"publisher\":{\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/volkswagen-id3-segunda-mano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Volkswagen-ID.3-1110x577-1.jpg\",\"articleSection\":[\"Consejos\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/volkswagen-id3-segunda-mano\\\/\",\"url\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/volkswagen-id3-segunda-mano\\\/\",\"name\":\"Volkswagen ID3 segunda mano: Referente el\u00e9ctrico de ocasi\u00f3n - OcasionPlus Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/volkswagen-id3-segunda-mano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/volkswagen-id3-segunda-mano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Volkswagen-ID.3-1110x577-1.jpg\",\"datePublished\":\"2025-01-20T13:08:34+00:00\",\"dateModified\":\"2025-03-27T09:07:47+00:00\",\"description\":\"El Volkswagen ID3 de segunda mano ha ido ganando una gran popularidad gracias a sus m\u00faltiples configuraciones y a una notable autonom\u00eda.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/volkswagen-id3-segunda-mano\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/volkswagen-id3-segunda-mano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/volkswagen-id3-segunda-mano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Volkswagen-ID.3-1110x577-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Volkswagen-ID.3-1110x577-1.jpg\",\"width\":1110,\"height\":577,\"caption\":\"Volkswagen ID3 segunda mano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/noticias\\\/volkswagen-id3-segunda-mano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ocasionplus.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Volkswagen ID3 segunda mano: Referente el\u00e9ctrico de ocasi\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#website\",\"url\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/\",\"name\":\"OcasionPlus Blog\",\"description\":\"Veh\u00edculos de ocasi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#organization\",\"name\":\"OcasionPlus\",\"url\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-cropped-oplus-logo-blog.png\",\"contentUrl\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-cropped-oplus-logo-blog.png\",\"width\":360,\"height\":71,\"caption\":\"OcasionPlus\"},\"image\":{\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ocasionplus\",\"https:\\\/\\\/x.com\\\/ocasionplus\",\"https:\\\/\\\/www.instagram.com\\\/ocasion_plus\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCBiCAto61Lyu27CgI95wrYQ\",\"https:\\\/\\\/www.tiktok.com\\\/@ocasionplus.com\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/ocasionplus\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/noticias.grupoocasionplus.com\\\/#\\\/schema\\\/person\\\/7ab10ae859759ef2622b28e83ba868eb\",\"name\":\"OcasionPlus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/ocasionplus_avatar-96x96.jpg\",\"url\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/ocasionplus_avatar-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ocasionplus.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/ocasionplus_avatar-96x96.jpg\",\"caption\":\"OcasionPlus\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Volkswagen ID3 segunda mano: Referente el\u00e9ctrico de ocasi\u00f3n - OcasionPlus Blog","description":"El Volkswagen ID3 de segunda mano ha ido ganando una gran popularidad gracias a sus m\u00faltiples configuraciones y a una notable autonom\u00eda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ocasionplus.com\/noticias\/volkswagen-id3-segunda-mano\/","og_locale":"es_ES","og_type":"article","og_title":"Volkswagen ID3 segunda mano: Referente el\u00e9ctrico de ocasi\u00f3n","og_description":"El Volkswagen ID3 de segunda mano ha ido ganando una gran popularidad gracias a sus m\u00faltiples configuraciones y a una notable autonom\u00eda.","og_url":"https:\/\/www.ocasionplus.com\/noticias\/volkswagen-id3-segunda-mano\/","og_site_name":"OcasionPlus Blog","article_publisher":"https:\/\/www.facebook.com\/ocasionplus","article_published_time":"2025-01-20T13:08:34+00:00","article_modified_time":"2025-03-27T09:07:47+00:00","og_image":[{"width":1110,"height":577,"url":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2025\/01\/Volkswagen-ID.3-1110x577-1.jpg","type":"image\/jpeg"}],"author":"OcasionPlus","twitter_card":"summary_large_image","twitter_creator":"@ocasionplus","twitter_site":"@ocasionplus","twitter_misc":{"Escrito por":"OcasionPlus","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ocasionplus.com\/noticias\/volkswagen-id3-segunda-mano\/#article","isPartOf":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/volkswagen-id3-segunda-mano\/"},"author":{"name":"OcasionPlus","@id":"https:\/\/noticias.grupoocasionplus.com\/#\/schema\/person\/7ab10ae859759ef2622b28e83ba868eb"},"headline":"Volkswagen ID3 segunda mano: Referente el\u00e9ctrico de ocasi\u00f3n","datePublished":"2025-01-20T13:08:34+00:00","dateModified":"2025-03-27T09:07:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/volkswagen-id3-segunda-mano\/"},"wordCount":1926,"publisher":{"@id":"https:\/\/noticias.grupoocasionplus.com\/#organization"},"image":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/volkswagen-id3-segunda-mano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2025\/01\/Volkswagen-ID.3-1110x577-1.jpg","articleSection":["Consejos"],"inLanguage":"es","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.ocasionplus.com\/noticias\/volkswagen-id3-segunda-mano\/","url":"https:\/\/www.ocasionplus.com\/noticias\/volkswagen-id3-segunda-mano\/","name":"Volkswagen ID3 segunda mano: Referente el\u00e9ctrico de ocasi\u00f3n - OcasionPlus Blog","isPartOf":{"@id":"https:\/\/noticias.grupoocasionplus.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/volkswagen-id3-segunda-mano\/#primaryimage"},"image":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/volkswagen-id3-segunda-mano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2025\/01\/Volkswagen-ID.3-1110x577-1.jpg","datePublished":"2025-01-20T13:08:34+00:00","dateModified":"2025-03-27T09:07:47+00:00","description":"El Volkswagen ID3 de segunda mano ha ido ganando una gran popularidad gracias a sus m\u00faltiples configuraciones y a una notable autonom\u00eda.","breadcrumb":{"@id":"https:\/\/www.ocasionplus.com\/noticias\/volkswagen-id3-segunda-mano\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ocasionplus.com\/noticias\/volkswagen-id3-segunda-mano\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ocasionplus.com\/noticias\/volkswagen-id3-segunda-mano\/#primaryimage","url":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2025\/01\/Volkswagen-ID.3-1110x577-1.jpg","contentUrl":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2025\/01\/Volkswagen-ID.3-1110x577-1.jpg","width":1110,"height":577,"caption":"Volkswagen ID3 segunda mano"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ocasionplus.com\/noticias\/volkswagen-id3-segunda-mano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ocasionplus.com\/"},{"@type":"ListItem","position":2,"name":"Volkswagen ID3 segunda mano: Referente el\u00e9ctrico de ocasi\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noticias.grupoocasionplus.com\/#website","url":"https:\/\/noticias.grupoocasionplus.com\/","name":"OcasionPlus Blog","description":"Veh\u00edculos de ocasi\u00f3n","publisher":{"@id":"https:\/\/noticias.grupoocasionplus.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticias.grupoocasionplus.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticias.grupoocasionplus.com\/#organization","name":"OcasionPlus","url":"https:\/\/noticias.grupoocasionplus.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticias.grupoocasionplus.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/05\/cropped-cropped-oplus-logo-blog.png","contentUrl":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/05\/cropped-cropped-oplus-logo-blog.png","width":360,"height":71,"caption":"OcasionPlus"},"image":{"@id":"https:\/\/noticias.grupoocasionplus.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ocasionplus","https:\/\/x.com\/ocasionplus","https:\/\/www.instagram.com\/ocasion_plus","https:\/\/www.youtube.com\/channel\/UCBiCAto61Lyu27CgI95wrYQ","https:\/\/www.tiktok.com\/@ocasionplus.com","https:\/\/es.linkedin.com\/company\/ocasionplus"]},{"@type":"Person","@id":"https:\/\/noticias.grupoocasionplus.com\/#\/schema\/person\/7ab10ae859759ef2622b28e83ba868eb","name":"OcasionPlus","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/07\/ocasionplus_avatar-96x96.jpg","url":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/07\/ocasionplus_avatar-96x96.jpg","contentUrl":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2024\/07\/ocasionplus_avatar-96x96.jpg","caption":"OcasionPlus"}}]}},"jetpack_featured_media_url":"https:\/\/www.ocasionplus.com\/wp-content\/uploads\/2025\/01\/Volkswagen-ID.3-1110x577-1.jpg","_links":{"self":[{"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/posts\/14873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/comments?post=14873"}],"version-history":[{"count":3,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/posts\/14873\/revisions"}],"predecessor-version":[{"id":14885,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/posts\/14873\/revisions\/14885"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/media\/14874"}],"wp:attachment":[{"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/media?parent=14873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/categories?post=14873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ocasionplus.com\/noticias\/wp-json\/wp\/v2\/tags?post=14873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}